{"id":1906,"date":"2022-01-13T19:10:48","date_gmt":"2022-01-13T12:10:48","guid":{"rendered":"https:\/\/www.bangkokcrafter.com\/?post_type=product&#038;p=1906"},"modified":"2022-01-14T11:14:14","modified_gmt":"2022-01-14T04:14:14","slug":"%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9b%e0%b9%8b%e0%b8%b2%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%95%e0%b8%9a%e0%b8%8a%e0%b8%a7%e0%b8%b2-bg04-20020v","status":"publish","type":"product","link":"https:\/\/www.bangkokcrafter.com\/zh-hant\/product\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9b%e0%b9%8b%e0%b8%b2%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%95%e0%b8%9a%e0%b8%8a%e0%b8%a7%e0%b8%b2-bg04-20020v\/","title":{"rendered":"\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32"},"content":{"rendered":"<p>\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e2e\u0e19\u0e40\u0e21\u0e14\u0e08\u0e32\u0e01 \u201c\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32\u201d \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e21\u0e35\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e17\u0e35\u0e48\u0e27\u0e34\u0e08\u0e34\u0e15\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e2a\u0e32\u0e19\u0e41\u0e25\u0e30\u0e21\u0e35\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e15\u0e31\u0e27\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e31\u0e01\u0e2a\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e04\u0e23\u0e1a \u0e17\u0e19\u0e17\u0e32\u0e19 \u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19<br \/>\n\u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e08\u0e32\u0e01 \u201c\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32\u201d \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e19\u0e33\u0e25\u0e33\u0e15\u0e49\u0e19\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49 \u0e21\u0e32\u0e41\u0e22\u0e01\u0e2a\u0e01\u0e31\u0e14\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e40\u0e0a\u0e34\u0e07\u0e01\u0e25 \u0e1b\u0e23\u0e32\u0e28\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e1b\u0e31\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e16\u0e31\u0e01\u0e17\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e37\u0e19\u0e1c\u0e49\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e2b\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15<\/p>\n<p><strong>\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32<\/strong><\/p>\n<ul>\n<li>\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e43\u0e2a\u0e48\u0e02\u0e2d\u0e07\u0e25\u0e07\u0e43\u0e19\u0e15\u0e30\u0e01\u0e23\u0e49\u0e32\u0e08\u0e19\u0e41\u0e19\u0e48\u0e19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e1b\u0e17\u0e23\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e30\u0e01\u0e23\u0e49\u0e32\u0e16\u0e39\u0e01\u0e1a\u0e35\u0e1a\u0e08\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e17\u0e23\u0e07<\/li>\n<li>\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e19\u0e33\u0e21\u0e32\u0e1c\u0e36\u0e48\u0e07\u0e41\u0e14\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e46. \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e04\u0e07\u0e17\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e30\u0e01\u0e23\u0e49\u0e32<\/li>\n<li>\u0e2b\u0e25\u0e35\u0e01\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e01\u0e32\u0e23\u0e42\u0e14\u0e19\u0e19\u0e49\u0e33.\u0e16\u0e49\u0e32\u0e2b\u0e32\u0e01\u0e42\u0e14\u0e19\u0e19\u0e49\u0e33 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e37\u0e49\u0e19 \u0e43\u0e2b\u0e49\u0e19\u0e33\u0e44\u0e1b\u0e15\u0e32\u0e01\u0e41\u0e14\u0e14\u0e17\u0e31\u0e19\u0e17\u0e35\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32 1-2\u0e0a\u0e21<\/li>\n<li>\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e0a\u0e37\u0e49\u0e19 \u0e04\u0e27\u0e23\u0e19\u0e33\u0e15\u0e30\u0e01\u0e23\u0e49\u0e32\u0e43\u0e2a\u0e48\u0e16\u0e38\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1c\u0e19\u0e36\u0e01\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e19 \u0e21\u0e34\u0e14\u0e0a\u0e34\u0e14 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2b\u0e49\u0e07<\/li>\n<li>\u0e2b\u0e49\u0e32\u0e21\u0e01\u0e14\u0e17\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32. \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e1c\u0e34\u0e14\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e17\u0e23\u0e07.<\/li>\n<li>\u0e04\u0e27\u0e23\u0e19\u0e33\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2b\u0e23\u0e37\u0e2d\u0e1f\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e22\u0e31\u0e14\u0e44\u0e27\u0e49\u0e02\u0e49\u0e32\u0e07\u0e43\u0e19\u0e15\u0e30\u0e01\u0e23\u0e49\u0e32. \u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e43\u0e2a\u0e48\u0e02\u0e2d\u0e07\u0e25\u0e07\u0e43\u0e19\u0e15\u0e30\u0e01\u0e23\u0e49\u0e32\u0e08\u0e19\u0e41\u0e19\u0e48\u0e19<\/li>\n<\/ul>\n<p><strong>\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/strong><\/p>\n<ul>\n<li>\u0e43\u0e2a\u0e48\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e23\u0e30<\/li>\n<li>\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e16\u0e37\u0e2d<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e2e\u0e19\u0e40\u0e21\u0e14\u0e17\u0e23\u0e07\u0e21\u0e19 \u0e40\u0e2a\u0e49\u0e19\u0e25\u0e32\u0e22\u0e23\u0e27\u0e07\u0e02\u0e49\u0e32\u0e27\u0e08\u0e32\u0e01 \u201c\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32\u201d \u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e1c\u0e25\u0e21\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e08\u0e31\u0e1a\u0e17\u0e23\u0e07\u0e01\u0e25\u0e21\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e41\u0e02\u0e19 \u0e16\u0e37\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e34\u0e49\u0e27\u0e2a\u0e1a\u0e32\u0e22\u0e46 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e44\u0e1b\u0e1b\u0e34\u0e01\u0e19\u0e34\u0e04 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e01\u0e25\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 Spring &amp; Summer \u0e41\u0e1a\u0e1a\u0e0a\u0e34\u0e25\u0e46 \u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e27\u0e34\u0e19\u0e40\u0e17\u0e08<\/p>\n","protected":false},"featured_media":1909,"template":"","meta":[],"product_cat":[127,169],"product_tag":[173],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32 - www.bangkokcrafter.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bangkokcrafter.com\/product\/\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32-bg04-20020v\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32 - www.bangkokcrafter.com\" \/>\n<meta property=\"og:description\" content=\"\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e2e\u0e19\u0e40\u0e21\u0e14\u0e17\u0e23\u0e07\u0e21\u0e19 \u0e40\u0e2a\u0e49\u0e19\u0e25\u0e32\u0e22\u0e23\u0e27\u0e07\u0e02\u0e49\u0e32\u0e27\u0e08\u0e32\u0e01 \u201c\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32\u201d \u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e1c\u0e25\u0e21\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e08\u0e31\u0e1a\u0e17\u0e23\u0e07\u0e01\u0e25\u0e21\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e41\u0e02\u0e19 \u0e16\u0e37\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e34\u0e49\u0e27\u0e2a\u0e1a\u0e32\u0e22\u0e46 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e44\u0e1b\u0e1b\u0e34\u0e01\u0e19\u0e34\u0e04 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e01\u0e25\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 Spring &amp; Summer \u0e41\u0e1a\u0e1a\u0e0a\u0e34\u0e25\u0e46 \u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e27\u0e34\u0e19\u0e40\u0e17\u0e08\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bangkokcrafter.com\/product\/\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32-bg04-20020v\/\" \/>\n<meta property=\"og:site_name\" content=\"www.bangkokcrafter.com\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-14T04:14:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bangkokcrafter.com\/wp-content\/uploads\/2022\/01\/Bangkokcratfer-Wasserhyazinthe-WaterHyacinth-\u6c34\u846b\u82a6\u624b\u63d0\u5305-BG04-20020V-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"910\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bangkokcrafter.com\/product\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9b%e0%b9%8b%e0%b8%b2%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%95%e0%b8%9a%e0%b8%8a%e0%b8%a7%e0%b8%b2-bg04-20020v\/\",\"url\":\"https:\/\/www.bangkokcrafter.com\/product\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9b%e0%b9%8b%e0%b8%b2%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%95%e0%b8%9a%e0%b8%8a%e0%b8%a7%e0%b8%b2-bg04-20020v\/\",\"name\":\"\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32 - www.bangkokcrafter.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.bangkokcrafter.com\/en\/#website\"},\"datePublished\":\"2022-01-13T12:10:48+00:00\",\"dateModified\":\"2022-01-14T04:14:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bangkokcrafter.com\/product\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9b%e0%b9%8b%e0%b8%b2%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%95%e0%b8%9a%e0%b8%8a%e0%b8%a7%e0%b8%b2-bg04-20020v\/#breadcrumb\"},\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bangkokcrafter.com\/product\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9b%e0%b9%8b%e0%b8%b2%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%95%e0%b8%9a%e0%b8%8a%e0%b8%a7%e0%b8%b2-bg04-20020v\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bangkokcrafter.com\/product\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9b%e0%b9%8b%e0%b8%b2%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%95%e0%b8%9a%e0%b8%8a%e0%b8%a7%e0%b8%b2-bg04-20020v\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bangkokcrafter.com\/zh-hant\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.bangkokcrafter.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bangkokcrafter.com\/en\/#website\",\"url\":\"https:\/\/www.bangkokcrafter.com\/en\/\",\"name\":\"www.bangkokcrafter.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bangkokcrafter.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-TW\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32 - www.bangkokcrafter.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bangkokcrafter.com\/product\/\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32-bg04-20020v\/","og_locale":"zh_TW","og_type":"article","og_title":"\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32 - www.bangkokcrafter.com","og_description":"\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e2e\u0e19\u0e40\u0e21\u0e14\u0e17\u0e23\u0e07\u0e21\u0e19 \u0e40\u0e2a\u0e49\u0e19\u0e25\u0e32\u0e22\u0e23\u0e27\u0e07\u0e02\u0e49\u0e32\u0e27\u0e08\u0e32\u0e01 \u201c\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32\u201d \u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e1c\u0e25\u0e21\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e08\u0e31\u0e1a\u0e17\u0e23\u0e07\u0e01\u0e25\u0e21\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e41\u0e02\u0e19 \u0e16\u0e37\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e34\u0e49\u0e27\u0e2a\u0e1a\u0e32\u0e22\u0e46 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e44\u0e1b\u0e1b\u0e34\u0e01\u0e19\u0e34\u0e04 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e01\u0e25\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 Spring &amp; Summer \u0e41\u0e1a\u0e1a\u0e0a\u0e34\u0e25\u0e46 \u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e27\u0e34\u0e19\u0e40\u0e17\u0e08","og_url":"https:\/\/www.bangkokcrafter.com\/product\/\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32-bg04-20020v\/","og_site_name":"www.bangkokcrafter.com","article_modified_time":"2022-01-14T04:14:14+00:00","og_image":[{"width":650,"height":910,"url":"https:\/\/www.bangkokcrafter.com\/wp-content\/uploads\/2022\/01\/Bangkokcratfer-Wasserhyazinthe-WaterHyacinth-\u6c34\u846b\u82a6\u624b\u63d0\u5305-BG04-20020V-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bangkokcrafter.com\/product\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9b%e0%b9%8b%e0%b8%b2%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%95%e0%b8%9a%e0%b8%8a%e0%b8%a7%e0%b8%b2-bg04-20020v\/","url":"https:\/\/www.bangkokcrafter.com\/product\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9b%e0%b9%8b%e0%b8%b2%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%95%e0%b8%9a%e0%b8%8a%e0%b8%a7%e0%b8%b2-bg04-20020v\/","name":"\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32 - www.bangkokcrafter.com","isPartOf":{"@id":"https:\/\/www.bangkokcrafter.com\/en\/#website"},"datePublished":"2022-01-13T12:10:48+00:00","dateModified":"2022-01-14T04:14:14+00:00","breadcrumb":{"@id":"https:\/\/www.bangkokcrafter.com\/product\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9b%e0%b9%8b%e0%b8%b2%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%95%e0%b8%9a%e0%b8%8a%e0%b8%a7%e0%b8%b2-bg04-20020v\/#breadcrumb"},"inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bangkokcrafter.com\/product\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9b%e0%b9%8b%e0%b8%b2%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%95%e0%b8%9a%e0%b8%8a%e0%b8%a7%e0%b8%b2-bg04-20020v\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bangkokcrafter.com\/product\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9b%e0%b9%8b%e0%b8%b2%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%95%e0%b8%9a%e0%b8%8a%e0%b8%a7%e0%b8%b2-bg04-20020v\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bangkokcrafter.com\/zh-hant\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.bangkokcrafter.com\/shop\/"},{"@type":"ListItem","position":3,"name":"\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32"}]},{"@type":"WebSite","@id":"https:\/\/www.bangkokcrafter.com\/en\/#website","url":"https:\/\/www.bangkokcrafter.com\/en\/","name":"www.bangkokcrafter.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bangkokcrafter.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-TW"}]}},"_links":{"self":[{"href":"https:\/\/www.bangkokcrafter.com\/zh-hant\/wp-json\/wp\/v2\/product\/1906"}],"collection":[{"href":"https:\/\/www.bangkokcrafter.com\/zh-hant\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bangkokcrafter.com\/zh-hant\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bangkokcrafter.com\/zh-hant\/wp-json\/wp\/v2\/media\/1909"}],"wp:attachment":[{"href":"https:\/\/www.bangkokcrafter.com\/zh-hant\/wp-json\/wp\/v2\/media?parent=1906"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.bangkokcrafter.com\/zh-hant\/wp-json\/wp\/v2\/product_cat?post=1906"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.bangkokcrafter.com\/zh-hant\/wp-json\/wp\/v2\/product_tag?post=1906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}